{"id":1791,"date":"2026-01-19T22:50:41","date_gmt":"2026-01-19T21:50:41","guid":{"rendered":"https:\/\/taekwondo-saintpriest.fr\/?p=1791"},"modified":"2026-02-09T23:55:45","modified_gmt":"2026-02-09T22:55:45","slug":"direction-la-drome-le-club-sera-a-la-coupe-espoirs-de-livron","status":"publish","type":"post","link":"https:\/\/taekwondo-saintpriest.fr\/index.php\/2026\/01\/19\/direction-la-drome-le-club-sera-a-la-coupe-espoirs-de-livron\/","title":{"rendered":"Direction la Dr\u00f4me : Le club sera \u00e0 la Coupe Espoirs de Livron !"},"content":{"rendered":"\n<p>\u00c0 vos agendas ! Apr\u00e8s les excellents r\u00e9sultats obtenus \u00e0 Annecy, la Team Saint-Priest se pr\u00e9pare pour son prochain d\u00e9fi.\u00a0Le\u00a0<strong>dimanche 25 janvier 2026<\/strong>, nos comp\u00e9titeurs prendront la direction de Livron-sur-Dr\u00f4me pour participer \u00e0 la\u00a0<strong>Coupe Espoirs<\/strong>\u00a0organis\u00e9e par le Taekwondo Livron.<\/p>\n\n\n\n<p>Cette comp\u00e9tition, qui se d\u00e9roulera au Gymnase Claude Bon, est une \u00e9tape importante pour nos athl\u00e8tes des cat\u00e9gories\u00a0<strong>Benjamins, Minimes, Cadets, Juniors et Espoirs<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les infos pratiques :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Date :<\/strong>\u00a0Dimanche 25 janvier 2026\u00a0<\/li>\n\n\n\n<li><strong>Lieu :<\/strong>\u00a0<br>Gymnase Claude Bon, <br>2 rue Sabli\u00e8re, <br>26250 Livron-sur-Dr\u00f4me\u00a0<\/li>\n\n\n\n<li><strong>D\u00e9but des combats :<\/strong>\u00a008h30\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Nous comptons sur votre \u00e9nergie pour venir encourager nos jeunes combattants et les pousser vers de nouveaux podiums.<\/p>\n\n\n\n<p><strong>On se retrouve \u00e0 Livron pour porter haut les couleurs de Saint-Priest !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 vos agendas ! Apr\u00e8s les excellents r\u00e9sultats obtenus \u00e0 Annecy, la Team Saint-Priest se pr\u00e9pare pour son prochain d\u00e9fi.\u00a0Le\u00a0dimanche 25 janvier 2026, nos comp\u00e9titeurs prendront la direction de Livron-sur-Dr\u00f4me pour participer \u00e0 la\u00a0Coupe Espoirs\u00a0organis\u00e9e par le Taekwondo Livron. Cette comp\u00e9tition, qui se d\u00e9roulera au Gymnase Claude Bon, est une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1791","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/posts\/1791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1791"}],"version-history":[{"count":1,"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/posts\/1791\/revisions"}],"predecessor-version":[{"id":1795,"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/posts\/1791\/revisions\/1795"}],"wp:attachment":[{"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taekwondo-saintpriest.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}